{"id":2369,"date":"2021-12-09T14:25:22","date_gmt":"2021-12-09T06:25:22","guid":{"rendered":"http:\/\/islanddhc.org.hk\/express\/?page_id=2369"},"modified":"2022-02-16T16:44:39","modified_gmt":"2022-02-16T08:44:39","slug":"volunteer-sc","status":"publish","type":"page","link":"https:\/\/islanddhc.org.hk\/express\/zh-hans\/volunteer-sc\/","title":{"rendered":"\u6210\u4e3a\u4e49\u5de5"},"content":{"rendered":"<p>[vc_row full_width=&#8221;stretch_row_content_no_spaces&#8221; el_class=&#8221;content-header-banner-section&#8221; css=&#8221;.vc_custom_1639462423334{background-color: #f4f4f4 !important;}&#8221;][vc_column el_class=&#8221;content-header-banner-inner custom-content-header&#8221;][vc_column_text]<\/p>\n<div class=\"crop\"><img title=\"\" src=\"\/wp-content\/uploads\/2021\/12\/banner7-new.jpg\" alt=\"\" \/><\/div>\n<p>[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column][vc_column_text]<\/p>\n<h1 class=\"custom-page-title\"><span class=\"underline\">\u6210\u4e3a\u4e49\u5de5<\/span><\/h1>\n<p>[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column][vc_column_text]<\/p>\n<h2>\u5982\u5e0c\u671b\u6210\u4e3a\u672c\u5065\u5eb7\u7ad9\u4e49\u5de5\uff0c\u8bf7\u7ec6\u9605\u4ee5\u4e0b\u8d44\u6599\u3002<\/h2>\n<p>[\/vc_column_text][vc_column_text]<style>#sp-ea-2375 .spcollapsing { height: 0; overflow: hidden; transition-property: height;transition-duration: 300ms;}#sp-ea-2375.sp-easy-accordion>.sp-ea-single {margin-bottom: 10px; border: 1px solid #e2e2e2; }#sp-ea-2375.sp-easy-accordion>.sp-ea-single>.ea-header a {color: #444;}#sp-ea-2375.sp-easy-accordion>.sp-ea-single>.sp-collapse>.ea-body {background: #fff; color: #444;}#sp-ea-2375.sp-easy-accordion>.sp-ea-single {background: #eee;}#sp-ea-2375.sp-easy-accordion>.sp-ea-single>.ea-header a .ea-expand-icon { float: right; color: #444;font-size: 16px;}#sp-ea-2375.sp-easy-accordion>.sp-ea-single>.ea-header a .ea-expand-icon {margin-right: 0;}<\/style><div id=\"sp_easy_accordion-1784133784\">\n<div id=\"sp-ea-2375\" class=\"sp-ea-one sp-easy-accordion\" data-ea-active=\"ea-click\" data-ea-mode=\"vertical\" data-preloader=\"\" data-scroll-active-item=\"\" data-offset-to-scroll=\"0\">\n\n<!-- Start accordion card div. -->\n<div class=\"ea-card ea-expand sp-ea-single\">\n\t<!-- Start accordion header. -->\n\t<h3 class=\"ea-header\">\n\t\t<!-- Add anchor tag for header. -->\n\t\t<a class=\"collapsed\" id=\"ea-header-23750\" role=\"button\" data-sptoggle=\"spcollapse\" data-sptarget=\"#collapse23750\" aria-controls=\"collapse23750\" href=\"#\"  aria-expanded=\"true\" tabindex=\"0\">\n\t\t<i aria-hidden=\"true\" role=\"presentation\" class=\"ea-expand-icon eap-icon-ea-expand-minus\"><\/i> \u7533\u8bf7\u6210\u4e3a\u4e49\u5de5 (\u4e2a\u4eba\u4e49\u5de5\u9002\u7528)\t\t<\/a> <!-- Close anchor tag for header. -->\n\t<\/h3>\t<!-- Close header tag. -->\n\t<!-- Start collapsible content div. -->\n\t<div class=\"sp-collapse spcollapse collapsed show\" id=\"collapse23750\" data-parent=\"#sp-ea-2375\" role=\"region\" aria-labelledby=\"ea-header-23750\">  <!-- Content div. -->\n\t\t<div class=\"ea-body\">\n\t\t<p>\u5e74\u6ee116\u5c81\u6709\u5174\u8da3\u53c2\u4e0e\u4e49\u5de5\u670d\u52a1\u4e4b\u4eba\u58eb \u6216<\/p>\n<p>6 \u2013 15\u5c81\u7684\u7533\u8bf7\u4eba\u987b\u7531\u5bb6\u957f \/ \u76d1\u62a4\u4eba\u540c\u610f\u7b7e\u7f72<\/p>\n\t\t<\/div> <!-- Close content div. -->\n\t<\/div> <!-- Close collapse div. -->\n<\/div> <!-- Close card div. -->\n<!-- Start accordion card div. -->\n<div class=\"ea-card ea-expand sp-ea-single\">\n\t<!-- Start accordion header. -->\n\t<h3 class=\"ea-header\">\n\t\t<!-- Add anchor tag for header. -->\n\t\t<a class=\"collapsed\" id=\"ea-header-23751\" role=\"button\" data-sptoggle=\"spcollapse\" data-sptarget=\"#collapse23751\" aria-controls=\"collapse23751\" href=\"#\"  aria-expanded=\"true\" tabindex=\"0\">\n\t\t<i aria-hidden=\"true\" role=\"presentation\" class=\"ea-expand-icon eap-icon-ea-expand-minus\"><\/i> \u7533\u8bf7\u6210\u4e3a\u4e49\u5de5 (\u516c\u53f8\/\u56e2\u4f53\u9002\u7528)\t\t<\/a> <!-- Close anchor tag for header. -->\n\t<\/h3>\t<!-- Close header tag. -->\n\t<!-- Start collapsible content div. -->\n\t<div class=\"sp-collapse spcollapse collapsed show\" id=\"collapse23751\" data-parent=\"#sp-ea-2375\" role=\"region\" aria-labelledby=\"ea-header-23751\">  <!-- Content div. -->\n\t\t<div class=\"ea-body\">\n\t\t<p>\u51e1\u6709\u5174\u8da3\u7ec4\u7ec7 \/ \u53c2\u4e0e\u4e49\u52a1\u5de5\u4f5c\u7684\u516c\u53f8\u6216\u56e2\u4f53<\/p>\n\t\t<\/div> <!-- Close content div. -->\n\t<\/div> <!-- Close collapse div. -->\n<\/div> <!-- Close card div. -->\n<!-- Start accordion card div. -->\n<div class=\"ea-card ea-expand sp-ea-single\">\n\t<!-- Start accordion header. -->\n\t<h3 class=\"ea-header\">\n\t\t<!-- Add anchor tag for header. -->\n\t\t<a class=\"collapsed\" id=\"ea-header-23752\" role=\"button\" data-sptoggle=\"spcollapse\" data-sptarget=\"#collapse23752\" aria-controls=\"collapse23752\" href=\"#\"  aria-expanded=\"true\" tabindex=\"0\">\n\t\t<i aria-hidden=\"true\" role=\"presentation\" class=\"ea-expand-icon eap-icon-ea-expand-minus\"><\/i> \u7533\u8bf7\u6210\u4e3a\u5065\u5eb7\u5927\u4f7f\t\t<\/a> <!-- Close anchor tag for header. -->\n\t<\/h3>\t<!-- Close header tag. -->\n\t<!-- Start collapsible content div. -->\n\t<div class=\"sp-collapse spcollapse collapsed show\" id=\"collapse23752\" data-parent=\"#sp-ea-2375\" role=\"region\" aria-labelledby=\"ea-header-23752\">  <!-- Content div. -->\n\t\t<div class=\"ea-body\">\n\t\t<p>\u5e74\u6ee116\u5c81, \u6709\u5174\u8da3\u53c2\u4e0e\u4e49\u5de5\u670d\u52a1\u4e4b\u4eba\u58eb \u6216<\/p>\n<p>6-15\u5c81\u7684\u7533\u8bf7\u4eba\u987b\u7531\u5bb6\u957f\/\u76d1\u62a4\u4eba\u540c\u610f\u7b7e\u7f72<\/p>\n\t\t<\/div> <!-- Close content div. -->\n\t<\/div> <!-- Close collapse div. -->\n<\/div> <!-- Close card div. -->\n<!-- Start accordion card div. -->\n<div class=\"ea-card ea-expand sp-ea-single\">\n\t<!-- Start accordion header. -->\n\t<h3 class=\"ea-header\">\n\t\t<!-- Add anchor tag for header. -->\n\t\t<a class=\"collapsed\" id=\"ea-header-23753\" role=\"button\" data-sptoggle=\"spcollapse\" data-sptarget=\"#collapse23753\" aria-controls=\"collapse23753\" href=\"#\"  aria-expanded=\"true\" tabindex=\"0\">\n\t\t<i aria-hidden=\"true\" role=\"presentation\" class=\"ea-expand-icon eap-icon-ea-expand-minus\"><\/i> \u4e49\u5de5\u670d\u52a1\u7c7b\u522b\t\t<\/a> <!-- Close anchor tag for header. -->\n\t<\/h3>\t<!-- Close header tag. -->\n\t<!-- Start collapsible content div. -->\n\t<div class=\"sp-collapse spcollapse collapsed show\" id=\"collapse23753\" data-parent=\"#sp-ea-2375\" role=\"region\" aria-labelledby=\"ea-header-23753\">  <!-- Content div. -->\n\t\t<div class=\"ea-body\">\n\t\t<p><strong>\u5065\u5eb7\u670d\u52a1\uff1a<\/strong><br \/>\n\u5065\u5eb7\u68c0\u6d4b\u53ca\u8bc4\u4f30\u3001\u5065\u5eb7\u6559\u80b2\u63a8\u5e7f\u3001\u5065\u5eb7\u5668\u6750\u8fd0\u7528\u3001\u8fd0\u52a8\u793a\u8303\u3001\u533b\u7597\u62a4\u7406<\/p>\n<p><strong>\u793e\u533a\u670d\u52a1\uff1a<\/strong><br \/>\n\u5173\u6000\u63a2\u8bbf\u3001\u8857\u7ad9\u63a8\u5e7f\u3001\u5927\u5802\u54a8\u8be2\u3001\u7535\u8bdd\u8054\u7edc\u3001\u7eff\u5316\u73af\u5883<\/p>\n<p><strong>\u6d3b\u52a8\u63a8\u5c55\uff1a<\/strong><br \/>\n\u6d3b\u52a8\u7b56\u5212\u3001\u73ed\u7ec4\u5bfc\u5e08\/\u52a9\u7406\u3001\u5bfc\u8d4f\u5458\u3001\u6d3b\u52a8\u6444\u5f71\/\u5f55\u5f71\u3001\u6d3b\u52a8\u53f8\u4eea\/\u52a9\u7406<\/p>\n<p><strong>\u7f16\u8f91\u51fa\u7248\uff1a<\/strong><br \/>\n\u7f8e\u672f\u8bbe\u8ba1\u3001\u8d44\u6599\u8f93\u5165\u3001\u6587\u4ef6\u7ffb\u8bd1<\/p>\n\t\t<\/div> <!-- Close content div. -->\n\t<\/div> <!-- Close collapse div. -->\n<\/div> <!-- Close card div. -->\n<!-- Start accordion card div. -->\n<div class=\"ea-card ea-expand sp-ea-single\">\n\t<!-- Start accordion header. -->\n\t<h3 class=\"ea-header\">\n\t\t<!-- Add anchor tag for header. -->\n\t\t<a class=\"collapsed\" id=\"ea-header-23754\" role=\"button\" data-sptoggle=\"spcollapse\" data-sptarget=\"#collapse23754\" aria-controls=\"collapse23754\" href=\"#\"  aria-expanded=\"true\" tabindex=\"0\">\n\t\t<i aria-hidden=\"true\" role=\"presentation\" class=\"ea-expand-icon eap-icon-ea-expand-minus\"><\/i> \u5065\u5eb7\u5927\u4f7f\u670d\u52a1\u7c7b\u522b\t\t<\/a> <!-- Close anchor tag for header. -->\n\t<\/h3>\t<!-- Close header tag. -->\n\t<!-- Start collapsible content div. -->\n\t<div class=\"sp-collapse spcollapse collapsed show\" id=\"collapse23754\" data-parent=\"#sp-ea-2375\" role=\"region\" aria-labelledby=\"ea-header-23754\">  <!-- Content div. -->\n\t\t<div class=\"ea-body\">\n\t\t<p><strong>\u5065\u5eb7\u5927\u4f7f\uff1a<\/strong><br \/>\n\u8054\u540c\u62a4\u58eb\u53ca\u8f85\u52a9\u533b\u7597\u4eba\u5458\u89e3\u7b54\u5065\u5eb7\u67e5\u8be2<\/p>\n<p><strong>\u5065\u5eb7\u670d\u52a1\uff1a<\/strong><br \/>\n\u534f\u52a9\u5065\u5eb7\u68c0\u6d4b\u53ca\u8bc4\u4f30\u3001\u5065\u5eb7\u6559\u80b2\u63a8\u5e7f<\/p>\n<p>- \u534f\u52a9\u5065\u5eb7\u68c0\u6d4b\u3001\u6559\u80b2\u63a8\u5e7f\u3001\u5065\u5eb7\u5668\u6750\u8fd0\u7528\u3001\u8fd0\u52a8\u793a\u8303\u3001\u533b\u7597\u62a4\u7406<\/p>\n<p><strong>\u6d3b\u52a8\u63a8\u5e7f\uff1a<\/strong><br \/>\n\u6d3b\u52a8\u7b56\u5212\u3001\u534f\u4f5c<\/p>\n<p>- \u6d3b\u52a8\u7b56\u5212\u3001\u73ed\u7ec4\u5bfc\u5e08\/\u52a9\u7406\u3001\u6d3b\u52a8\u6444\u5f71\/\u5f55\u5f71\u3001\u6d3b\u52a8\u53f8\u4eea\/\u52a9\u7406<\/p>\n\t\t<\/div> <!-- Close content div. -->\n\t<\/div> <!-- Close collapse div. -->\n<\/div> <!-- Close card div. -->\n<!-- Start accordion card div. -->\n<div class=\"ea-card ea-expand sp-ea-single\">\n\t<!-- Start accordion header. -->\n\t<h3 class=\"ea-header\">\n\t\t<!-- Add anchor tag for header. -->\n\t\t<a class=\"collapsed\" id=\"ea-header-23755\" role=\"button\" data-sptoggle=\"spcollapse\" data-sptarget=\"#collapse23755\" aria-controls=\"collapse23755\" href=\"#\"  aria-expanded=\"true\" tabindex=\"0\">\n\t\t<i aria-hidden=\"true\" role=\"presentation\" class=\"ea-expand-icon eap-icon-ea-expand-minus\"><\/i> \u4e49\u5de5\u57f9\u8bad\t\t<\/a> <!-- Close anchor tag for header. -->\n\t<\/h3>\t<!-- Close header tag. -->\n\t<!-- Start collapsible content div. -->\n\t<div class=\"sp-collapse spcollapse collapsed show\" id=\"collapse23755\" data-parent=\"#sp-ea-2375\" role=\"region\" aria-labelledby=\"ea-header-23755\">  <!-- Content div. -->\n\t\t<div class=\"ea-body\">\n\t\t<p>\u4e49\u52a1\u5de5\u4f5c\u5bfc\u5411<\/p>\n<p>\u4e49\u52a1\u5de5\u4f5c\u57fa\u7840\u57f9\u8bad<\/p>\n<p>\u4e49\u52a1\u5de5\u4f5c\u6280\u5de7<\/p>\n<p>\u5065\u5eb7\u77e5\u8bc6\/\u5065\u5eb7\u68c0\u6d4b\u53ca\u8bc4\u4f30\u6280\u5de7<\/p>\n<p>\u5e26\u9886\/\u534f\u52a9\u6d3b\u52a8\u77e5\u8bc6<\/p>\n\t\t<\/div> <!-- Close content div. -->\n\t<\/div> <!-- Close collapse div. -->\n<\/div> <!-- Close card div. -->\n<!-- Start accordion card div. -->\n<div class=\"ea-card ea-expand sp-ea-single\">\n\t<!-- Start accordion header. -->\n\t<h3 class=\"ea-header\">\n\t\t<!-- Add anchor tag for header. -->\n\t\t<a class=\"collapsed\" id=\"ea-header-23756\" role=\"button\" data-sptoggle=\"spcollapse\" data-sptarget=\"#collapse23756\" aria-controls=\"collapse23756\" href=\"#\"  aria-expanded=\"true\" tabindex=\"0\">\n\t\t<i aria-hidden=\"true\" role=\"presentation\" class=\"ea-expand-icon eap-icon-ea-expand-minus\"><\/i> \u4e0b\u8f7d\u533a\t\t<\/a> <!-- Close anchor tag for header. -->\n\t<\/h3>\t<!-- Close header tag. -->\n\t<!-- Start collapsible content div. -->\n\t<div class=\"sp-collapse spcollapse collapsed show\" id=\"collapse23756\" data-parent=\"#sp-ea-2375\" role=\"region\" aria-labelledby=\"ea-header-23756\">  <!-- Content div. -->\n\t\t<div class=\"ea-body\">\n\t\t<p>\u6682\u65e0\u5185\u5bb9<\/p>\n\t\t<\/div> <!-- Close content div. -->\n\t<\/div> <!-- Close collapse div. -->\n<\/div> <!-- Close card div. -->\n<\/div>\n<\/div>\n[\/vc_column_text][\/vc_column][\/vc_row]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>[vc_row full_width=&#8221;stretch_row_content_no_spaces &hellip;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":""},"acf":[],"_links":{"self":[{"href":"https:\/\/islanddhc.org.hk\/express\/zh-hans\/wp-json\/wp\/v2\/pages\/2369"}],"collection":[{"href":"https:\/\/islanddhc.org.hk\/express\/zh-hans\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/islanddhc.org.hk\/express\/zh-hans\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/islanddhc.org.hk\/express\/zh-hans\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/islanddhc.org.hk\/express\/zh-hans\/wp-json\/wp\/v2\/comments?post=2369"}],"version-history":[{"count":13,"href":"https:\/\/islanddhc.org.hk\/express\/zh-hans\/wp-json\/wp\/v2\/pages\/2369\/revisions"}],"predecessor-version":[{"id":4048,"href":"https:\/\/islanddhc.org.hk\/express\/zh-hans\/wp-json\/wp\/v2\/pages\/2369\/revisions\/4048"}],"wp:attachment":[{"href":"https:\/\/islanddhc.org.hk\/express\/zh-hans\/wp-json\/wp\/v2\/media?parent=2369"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}